{"id":165195,"date":"2024-07-18T09:35:42","date_gmt":"2024-07-18T06:35:42","guid":{"rendered":"https:\/\/www.luckytackle.eu\/produktas\/seryklele-feeders-xxl100-grip\/"},"modified":"2026-06-24T12:17:57","modified_gmt":"2026-06-24T09:17:57","slug":"seryklele-feeders-xxl100-grip","status":"publish","type":"product","link":"https:\/\/www.luckytackle.eu\/en\/product\/seryklele-feeders-xxl100-grip\/","title":{"rendered":"Feeder cage RP Cage Feeders XXL100-Grip atvira"},"content":{"rendered":"<p>\u0160erykl\u0117l\u0117 Feeder \u017e\u016bklei sukurta gaudymui ypa\u010d didel\u0117je srov\u0117je. \u0160erykl\u0117l\u0117s anten\u0117l\u0117s veikia lyg inkarai, kurie reguliuojasi. <strong>XXL Dydis: diametras 3,5 cm, auk\u0161tis 4,5 cm. T\u016bris 43 cm<sup>3<\/sup>. Svoris 100 g.<br \/>\n<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0160erykl\u0117l\u0117 Feeder \u017e\u016bklei sukurta gaudymui ypa\u010d didel\u0117je srov\u0117je. \u0160erykl\u0117l\u0117s anten\u0117l\u0117s veikia lyg inkarai, kurie reguliuojasi. Svoris 100g.<\/p>\n","protected":false},"featured_media":165162,"template":"","meta":[],"product_brand":[],"product_cat":[17729],"product_tag":[],"class_list":{"0":"post-165195","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-all-products-17729","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Feeder cage RP Cage Feeders XXL100-Grip atvira - Luckytackle.eu<\/title>\n<meta name=\"description\" content=\"\u0160erykl\u0117l\u0117 Feeder \u017e\u016bklei sukurta gaudymui ypa\u010d didel\u0117je srov\u0117je. \u0160erykl\u0117l\u0117s anten\u0117l\u0117s veikia lyg inkarai, kurie reguliuojasi. Svoris 100g.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.luckytackle.eu\/en\/product\/seryklele-feeders-xxl100-grip\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Feeder cage RP Cage Feeders XXL100-Grip atvira - Luckytackle.eu\" \/>\n<meta property=\"og:description\" content=\"\u0160erykl\u0117l\u0117 Feeder \u017e\u016bklei sukurta gaudymui ypa\u010d didel\u0117je srov\u0117je. \u0160erykl\u0117l\u0117s anten\u0117l\u0117s veikia lyg inkarai, kurie reguliuojasi. Svoris 100g.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.luckytackle.eu\/en\/product\/seryklele-feeders-xxl100-grip\/\" \/>\n<meta property=\"og:site_name\" content=\"Luckytackle.eu\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/luckytackle.eu\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-24T09:17:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.luckytackle.eu\/wp-content\/uploads\/2024\/07\/Seryklele-Feeders-XS50-Grip.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\/\/www.luckytackle.eu\/en\/product\/seryklele-feeders-xxl100-grip\/\",\"url\":\"https:\/\/www.luckytackle.eu\/en\/product\/seryklele-feeders-xxl100-grip\/\",\"name\":\"Feeder cage RP Cage Feeders XXL100-Grip atvira - Luckytackle.eu\",\"isPartOf\":{\"@id\":\"https:\/\/www.luckytackle.eu\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.luckytackle.eu\/en\/product\/seryklele-feeders-xxl100-grip\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.luckytackle.eu\/en\/product\/seryklele-feeders-xxl100-grip\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.luckytackle.eu\/wp-content\/uploads\/2024\/07\/Seryklele-Feeders-XS50-Grip.jpg\",\"datePublished\":\"2024-07-18T06:35:42+00:00\",\"dateModified\":\"2026-06-24T09:17:57+00:00\",\"description\":\"\u0160erykl\u0117l\u0117 Feeder \u017e\u016bklei sukurta gaudymui ypa\u010d didel\u0117je srov\u0117je. \u0160erykl\u0117l\u0117s anten\u0117l\u0117s veikia lyg inkarai, kurie reguliuojasi. Svoris 100g.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.luckytackle.eu\/en\/product\/seryklele-feeders-xxl100-grip\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.luckytackle.eu\/en\/product\/seryklele-feeders-xxl100-grip\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.luckytackle.eu\/en\/product\/seryklele-feeders-xxl100-grip\/#primaryimage\",\"url\":\"https:\/\/www.luckytackle.eu\/wp-content\/uploads\/2024\/07\/Seryklele-Feeders-XS50-Grip.jpg\",\"contentUrl\":\"https:\/\/www.luckytackle.eu\/wp-content\/uploads\/2024\/07\/Seryklele-Feeders-XS50-Grip.jpg\",\"width\":1500,\"height\":1500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.luckytackle.eu\/en\/product\/seryklele-feeders-xxl100-grip\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.luckytackle.eu\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/www.luckytackle.eu\/en\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Feeder cage RP Cage Feeders XXL100-Grip atvira\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.luckytackle.eu\/en\/#website\",\"url\":\"https:\/\/www.luckytackle.eu\/en\/\",\"name\":\"Luckytackle.eu\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.luckytackle.eu\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.luckytackle.eu\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.luckytackle.eu\/en\/#organization\",\"name\":\"LuckyTackle.eu\",\"url\":\"https:\/\/www.luckytackle.eu\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.luckytackle.eu\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.luckytackle.eu\/wp-content\/uploads\/2021\/09\/logo-1.png\",\"contentUrl\":\"https:\/\/www.luckytackle.eu\/wp-content\/uploads\/2021\/09\/logo-1.png\",\"width\":237,\"height\":88,\"caption\":\"LuckyTackle.eu\"},\"image\":{\"@id\":\"https:\/\/www.luckytackle.eu\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/luckytackle.eu\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Feeder cage RP Cage Feeders XXL100-Grip atvira - Luckytackle.eu","description":"\u0160erykl\u0117l\u0117 Feeder \u017e\u016bklei sukurta gaudymui ypa\u010d didel\u0117je srov\u0117je. \u0160erykl\u0117l\u0117s anten\u0117l\u0117s veikia lyg inkarai, kurie reguliuojasi. Svoris 100g.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.luckytackle.eu\/en\/product\/seryklele-feeders-xxl100-grip\/","og_locale":"en_US","og_type":"article","og_title":"Feeder cage RP Cage Feeders XXL100-Grip atvira - Luckytackle.eu","og_description":"\u0160erykl\u0117l\u0117 Feeder \u017e\u016bklei sukurta gaudymui ypa\u010d didel\u0117je srov\u0117je. \u0160erykl\u0117l\u0117s anten\u0117l\u0117s veikia lyg inkarai, kurie reguliuojasi. Svoris 100g.","og_url":"https:\/\/www.luckytackle.eu\/en\/product\/seryklele-feeders-xxl100-grip\/","og_site_name":"Luckytackle.eu","article_publisher":"https:\/\/www.facebook.com\/luckytackle.eu\/","article_modified_time":"2026-06-24T09:17:57+00:00","og_image":[{"width":1500,"height":1500,"url":"https:\/\/www.luckytackle.eu\/wp-content\/uploads\/2024\/07\/Seryklele-Feeders-XS50-Grip.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.luckytackle.eu\/en\/product\/seryklele-feeders-xxl100-grip\/","url":"https:\/\/www.luckytackle.eu\/en\/product\/seryklele-feeders-xxl100-grip\/","name":"Feeder cage RP Cage Feeders XXL100-Grip atvira - Luckytackle.eu","isPartOf":{"@id":"https:\/\/www.luckytackle.eu\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.luckytackle.eu\/en\/product\/seryklele-feeders-xxl100-grip\/#primaryimage"},"image":{"@id":"https:\/\/www.luckytackle.eu\/en\/product\/seryklele-feeders-xxl100-grip\/#primaryimage"},"thumbnailUrl":"https:\/\/www.luckytackle.eu\/wp-content\/uploads\/2024\/07\/Seryklele-Feeders-XS50-Grip.jpg","datePublished":"2024-07-18T06:35:42+00:00","dateModified":"2026-06-24T09:17:57+00:00","description":"\u0160erykl\u0117l\u0117 Feeder \u017e\u016bklei sukurta gaudymui ypa\u010d didel\u0117je srov\u0117je. \u0160erykl\u0117l\u0117s anten\u0117l\u0117s veikia lyg inkarai, kurie reguliuojasi. Svoris 100g.","breadcrumb":{"@id":"https:\/\/www.luckytackle.eu\/en\/product\/seryklele-feeders-xxl100-grip\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.luckytackle.eu\/en\/product\/seryklele-feeders-xxl100-grip\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.luckytackle.eu\/en\/product\/seryklele-feeders-xxl100-grip\/#primaryimage","url":"https:\/\/www.luckytackle.eu\/wp-content\/uploads\/2024\/07\/Seryklele-Feeders-XS50-Grip.jpg","contentUrl":"https:\/\/www.luckytackle.eu\/wp-content\/uploads\/2024\/07\/Seryklele-Feeders-XS50-Grip.jpg","width":1500,"height":1500},{"@type":"BreadcrumbList","@id":"https:\/\/www.luckytackle.eu\/en\/product\/seryklele-feeders-xxl100-grip\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.luckytackle.eu\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.luckytackle.eu\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Feeder cage RP Cage Feeders XXL100-Grip atvira"}]},{"@type":"WebSite","@id":"https:\/\/www.luckytackle.eu\/en\/#website","url":"https:\/\/www.luckytackle.eu\/en\/","name":"Luckytackle.eu","description":"","publisher":{"@id":"https:\/\/www.luckytackle.eu\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.luckytackle.eu\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.luckytackle.eu\/en\/#organization","name":"LuckyTackle.eu","url":"https:\/\/www.luckytackle.eu\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.luckytackle.eu\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.luckytackle.eu\/wp-content\/uploads\/2021\/09\/logo-1.png","contentUrl":"https:\/\/www.luckytackle.eu\/wp-content\/uploads\/2021\/09\/logo-1.png","width":237,"height":88,"caption":"LuckyTackle.eu"},"image":{"@id":"https:\/\/www.luckytackle.eu\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/luckytackle.eu\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.luckytackle.eu\/en\/wp-json\/wp\/v2\/product\/165195","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.luckytackle.eu\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.luckytackle.eu\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.luckytackle.eu\/en\/wp-json\/wp\/v2\/media\/165162"}],"wp:attachment":[{"href":"https:\/\/www.luckytackle.eu\/en\/wp-json\/wp\/v2\/media?parent=165195"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.luckytackle.eu\/en\/wp-json\/wp\/v2\/product_brand?post=165195"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.luckytackle.eu\/en\/wp-json\/wp\/v2\/product_cat?post=165195"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.luckytackle.eu\/en\/wp-json\/wp\/v2\/product_tag?post=165195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}