{"id":156655,"date":"2024-02-22T13:53:23","date_gmt":"2024-02-22T10:53:23","guid":{"rendered":"https:\/\/www.luckytackle.eu\/produktas\/silikoninis-masalas-herakles-benjo-xx-145cm-chartreuse\/"},"modified":"2026-06-24T12:24:48","modified_gmt":"2026-06-24T09:24:48","slug":"silikoninis-masalas-herakles-benjo-xx-145cm-chartreuse","status":"publish","type":"product","link":"https:\/\/www.luckytackle.eu\/en\/product\/silikoninis-masalas-herakles-benjo-xx-145cm-chartreuse\/","title":{"rendered":"Silicone lure Herakles BENJO XX 14,5cm (Chartreuse)"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":156579,"template":"","meta":[],"product_brand":[],"product_cat":[17729],"product_tag":[],"class_list":{"0":"post-156655","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-all-products-17729","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Silicone lure Herakles BENJO XX 14,5cm (Chartreuse) - Luckytackle.eu<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.luckytackle.eu\/en\/product\/silikoninis-masalas-herakles-benjo-xx-145cm-chartreuse\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Silicone lure Herakles BENJO XX 14,5cm (Chartreuse) - Luckytackle.eu\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.luckytackle.eu\/en\/product\/silikoninis-masalas-herakles-benjo-xx-145cm-chartreuse\/\" \/>\n<meta property=\"og:site_name\" content=\"Luckytackle.eu\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/luckytackle.eu\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-24T09:24:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.luckytackle.eu\/wp-content\/uploads\/2024\/02\/Silikoninis-masalas-Herakles-BENJO-XX-145cm-Chartreuse.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\/\/www.luckytackle.eu\/en\/product\/silikoninis-masalas-herakles-benjo-xx-145cm-chartreuse\/\",\"url\":\"https:\/\/www.luckytackle.eu\/en\/product\/silikoninis-masalas-herakles-benjo-xx-145cm-chartreuse\/\",\"name\":\"Silicone lure Herakles BENJO XX 14,5cm (Chartreuse) - Luckytackle.eu\",\"isPartOf\":{\"@id\":\"https:\/\/www.luckytackle.eu\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.luckytackle.eu\/en\/product\/silikoninis-masalas-herakles-benjo-xx-145cm-chartreuse\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.luckytackle.eu\/en\/product\/silikoninis-masalas-herakles-benjo-xx-145cm-chartreuse\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.luckytackle.eu\/wp-content\/uploads\/2024\/02\/Silikoninis-masalas-Herakles-BENJO-XX-145cm-Chartreuse.jpg\",\"datePublished\":\"2024-02-22T10:53:23+00:00\",\"dateModified\":\"2026-06-24T09:24:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.luckytackle.eu\/en\/product\/silikoninis-masalas-herakles-benjo-xx-145cm-chartreuse\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.luckytackle.eu\/en\/product\/silikoninis-masalas-herakles-benjo-xx-145cm-chartreuse\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.luckytackle.eu\/en\/product\/silikoninis-masalas-herakles-benjo-xx-145cm-chartreuse\/#primaryimage\",\"url\":\"https:\/\/www.luckytackle.eu\/wp-content\/uploads\/2024\/02\/Silikoninis-masalas-Herakles-BENJO-XX-145cm-Chartreuse.jpg\",\"contentUrl\":\"https:\/\/www.luckytackle.eu\/wp-content\/uploads\/2024\/02\/Silikoninis-masalas-Herakles-BENJO-XX-145cm-Chartreuse.jpg\",\"width\":400,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.luckytackle.eu\/en\/product\/silikoninis-masalas-herakles-benjo-xx-145cm-chartreuse\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.luckytackle.eu\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/www.luckytackle.eu\/en\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Silicone lure Herakles BENJO XX 14,5cm (Chartreuse)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.luckytackle.eu\/en\/#website\",\"url\":\"https:\/\/www.luckytackle.eu\/en\/\",\"name\":\"Luckytackle.eu\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.luckytackle.eu\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.luckytackle.eu\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.luckytackle.eu\/en\/#organization\",\"name\":\"LuckyTackle.eu\",\"url\":\"https:\/\/www.luckytackle.eu\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.luckytackle.eu\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.luckytackle.eu\/wp-content\/uploads\/2021\/09\/logo-1.png\",\"contentUrl\":\"https:\/\/www.luckytackle.eu\/wp-content\/uploads\/2021\/09\/logo-1.png\",\"width\":237,\"height\":88,\"caption\":\"LuckyTackle.eu\"},\"image\":{\"@id\":\"https:\/\/www.luckytackle.eu\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/luckytackle.eu\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Silicone lure Herakles BENJO XX 14,5cm (Chartreuse) - Luckytackle.eu","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.luckytackle.eu\/en\/product\/silikoninis-masalas-herakles-benjo-xx-145cm-chartreuse\/","og_locale":"en_US","og_type":"article","og_title":"Silicone lure Herakles BENJO XX 14,5cm (Chartreuse) - Luckytackle.eu","og_url":"https:\/\/www.luckytackle.eu\/en\/product\/silikoninis-masalas-herakles-benjo-xx-145cm-chartreuse\/","og_site_name":"Luckytackle.eu","article_publisher":"https:\/\/www.facebook.com\/luckytackle.eu\/","article_modified_time":"2026-06-24T09:24:48+00:00","og_image":[{"width":400,"height":400,"url":"https:\/\/www.luckytackle.eu\/wp-content\/uploads\/2024\/02\/Silikoninis-masalas-Herakles-BENJO-XX-145cm-Chartreuse.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.luckytackle.eu\/en\/product\/silikoninis-masalas-herakles-benjo-xx-145cm-chartreuse\/","url":"https:\/\/www.luckytackle.eu\/en\/product\/silikoninis-masalas-herakles-benjo-xx-145cm-chartreuse\/","name":"Silicone lure Herakles BENJO XX 14,5cm (Chartreuse) - Luckytackle.eu","isPartOf":{"@id":"https:\/\/www.luckytackle.eu\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.luckytackle.eu\/en\/product\/silikoninis-masalas-herakles-benjo-xx-145cm-chartreuse\/#primaryimage"},"image":{"@id":"https:\/\/www.luckytackle.eu\/en\/product\/silikoninis-masalas-herakles-benjo-xx-145cm-chartreuse\/#primaryimage"},"thumbnailUrl":"https:\/\/www.luckytackle.eu\/wp-content\/uploads\/2024\/02\/Silikoninis-masalas-Herakles-BENJO-XX-145cm-Chartreuse.jpg","datePublished":"2024-02-22T10:53:23+00:00","dateModified":"2026-06-24T09:24:48+00:00","breadcrumb":{"@id":"https:\/\/www.luckytackle.eu\/en\/product\/silikoninis-masalas-herakles-benjo-xx-145cm-chartreuse\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.luckytackle.eu\/en\/product\/silikoninis-masalas-herakles-benjo-xx-145cm-chartreuse\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.luckytackle.eu\/en\/product\/silikoninis-masalas-herakles-benjo-xx-145cm-chartreuse\/#primaryimage","url":"https:\/\/www.luckytackle.eu\/wp-content\/uploads\/2024\/02\/Silikoninis-masalas-Herakles-BENJO-XX-145cm-Chartreuse.jpg","contentUrl":"https:\/\/www.luckytackle.eu\/wp-content\/uploads\/2024\/02\/Silikoninis-masalas-Herakles-BENJO-XX-145cm-Chartreuse.jpg","width":400,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.luckytackle.eu\/en\/product\/silikoninis-masalas-herakles-benjo-xx-145cm-chartreuse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.luckytackle.eu\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.luckytackle.eu\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Silicone lure Herakles BENJO XX 14,5cm (Chartreuse)"}]},{"@type":"WebSite","@id":"https:\/\/www.luckytackle.eu\/en\/#website","url":"https:\/\/www.luckytackle.eu\/en\/","name":"Luckytackle.eu","description":"","publisher":{"@id":"https:\/\/www.luckytackle.eu\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.luckytackle.eu\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.luckytackle.eu\/en\/#organization","name":"LuckyTackle.eu","url":"https:\/\/www.luckytackle.eu\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.luckytackle.eu\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.luckytackle.eu\/wp-content\/uploads\/2021\/09\/logo-1.png","contentUrl":"https:\/\/www.luckytackle.eu\/wp-content\/uploads\/2021\/09\/logo-1.png","width":237,"height":88,"caption":"LuckyTackle.eu"},"image":{"@id":"https:\/\/www.luckytackle.eu\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/luckytackle.eu\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.luckytackle.eu\/en\/wp-json\/wp\/v2\/product\/156655","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.luckytackle.eu\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.luckytackle.eu\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.luckytackle.eu\/en\/wp-json\/wp\/v2\/media\/156579"}],"wp:attachment":[{"href":"https:\/\/www.luckytackle.eu\/en\/wp-json\/wp\/v2\/media?parent=156655"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.luckytackle.eu\/en\/wp-json\/wp\/v2\/product_brand?post=156655"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.luckytackle.eu\/en\/wp-json\/wp\/v2\/product_cat?post=156655"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.luckytackle.eu\/en\/wp-json\/wp\/v2\/product_tag?post=156655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}